{"id":43930,"date":"2024-08-20T10:33:35","date_gmt":"2024-08-20T08:33:35","guid":{"rendered":"https:\/\/blog.gymglish.com\/?p=43930"},"modified":"2025-04-03T11:13:27","modified_gmt":"2025-04-03T09:13:27","slug":"5-phrases-restaurant-anglophone","status":"publish","type":"post","link":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone","title":{"rendered":"Gastronomie, 5 phrases utiles \u00e0 retenir dans un restaurant anglophone"},"content":{"rendered":"\n<p><strong>Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.<\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Le patrimoine alimentaire des pays anglophones est aussi diversifi\u00e9 qu&#8217;excitant. <\/p>\n\n\n\n<p>Chaque personne apprenant une langue te dira que la possibilit\u00e9 de <a href=\"https:\/\/www.gymglish.com\/fr\/gymglish\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019utiliser et de la pratiquer<\/a> est l&#8217;aspect le plus gratifiant des voyages. <\/p>\n\n\n\n<p>Aujourd&#8217;hui, un nombre croissant de chefs talentueux ouvrent des restaurants dans des villes anim\u00e9es comme Portland, Sydney ou Vancouver, mais aussi dans des endroits plus tranquilles comme la c\u00f4te \u00e9cossaise ou les plages de Cornouailles, de quoi faire le tour gastronomique des pays anglophones.<\/p>\n\n\n\n<p>Bien souvent, un v\u00e9ritable gastronome se pr\u00e9cipite dans un restaurant local d\u00e8s l&#8217;atterrissage de l&#8217;avion. Mais que se passe-t-il apr\u00e8s avoir franchi la porte ?<\/p>\n\n\n\n<p>Nous sommes heureux de partager 5 expressions uniques et utiles qui am\u00e9lioreront ton exp\u00e9rience gastronomique lors de ton voyage dans un pays anglophone. Profites-en ! (une version audio de cet article est disponible sur notre page <a href=\"https:\/\/www.instagram.com\/reel\/Ck8YFybo5Dm\/?utm_source=ig_web_copy_link\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a> \ud83c\udfa7).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Do you have a table for one?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"740\" height=\"494\" data-attachment-id=\"30394\" data-permalink=\"https:\/\/blog.gymglish.com\/fr\/bettyanna-table-diner-couleur-1-2\" data-orig-file=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?fit=1280%2C854&amp;ssl=1\" data-orig-size=\"1280,854\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"BettyAnna-table-diner-couleur-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?fit=750%2C500&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?resize=740%2C494&#038;ssl=1\" alt=\"\" class=\"wp-image-30394\" style=\"width:609px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?resize=749%2C500&amp;ssl=1 749w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/BettyAnna-table-diner-couleur-1.png?w=1280&amp;ssl=1 1280w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n<\/div>\n\n\n<p>Bien que la traditionnelle <em>&#8220;table for two&#8221;<\/em> soit la plus couramment entendue, tu voudrais peut-\u00eatre \u00e9chapper au tumulte ext\u00e9rieur de la ville que tu visite et profiter d&#8217;un d\u00eener tranquille et romantique. Juste toi, ton t\u00e9l\u00e9phone et un verre de vin.<\/p>\n\n\n\n<p><strong>Exemple : <\/strong><em>Do you have a table for one? And the Wi-Fi code? Also I\u2019ll just have some bread and a glass of water.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">What are today\u2019s specials?<\/h2>\n\n\n\n<p>D&#8217;habitude, les plats du jour sont des mets uniques cr\u00e9\u00e9s en fonction des ingr\u00e9dients disponibles ce jour-l\u00e0. Nous te sugg\u00e9rons vivement de demander \u00e0 ton serveur les plats du jour et de le faire r\u00e9p\u00e9ter trois fois avant de commander le plat que tu avais pr\u00e9vu \u00e0 l&#8217;origine.<\/p>\n\n\n\n<p><strong>Conseil utile :<\/strong> Attention, car les plats du jour d&#8217;aujourd&#8217;hui sont souvent les d\u00e9chets de demain (\u00e0 m\u00e9diter).<\/p>\n\n\n\n<p><strong>Exemple :<\/strong> <em>\u2013 What are today\u2019s specials?<\/em><\/p>\n\n\n\n<p><em>\u2013 Swordfish nuggets.<\/em><\/p>\n\n\n\n<p><em>\u2013 That doesn\u2019t sound very special.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Do you have anything without meat?<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"740\" height=\"493\" data-attachment-id=\"30401\" data-permalink=\"https:\/\/blog.gymglish.com\/fr\/plate-of-meat-2\" data-orig-file=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?fit=960%2C640&amp;ssl=1\" data-orig-size=\"960,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"plate-of-meat\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?fit=750%2C500&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?resize=740%2C493&#038;ssl=1\" alt=\"\" class=\"wp-image-30401\" style=\"width:656px;height:auto\" srcset=\"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?resize=749%2C500&amp;ssl=1 749w, https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/01\/plate-of-meat.png?resize=750%2C500&amp;ssl=1 750w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/figure>\n<\/div>\n\n\n<p>Si tu es un amateur de v\u00e9g\u00e9tarisme ou aime partager tes repas avec ton lapin de compagnie, cette question te m\u00e8nera aux \u00e9tablissements les plus branch\u00e9s et respectueux des animaux.<\/p>\n\n\n\n<p><strong>Exemple : <\/strong><em>Do you have anything without meat? No? Ok, I\u2019ll have a steak, medium rare. Burger on the side, well done.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Can I speak to your manager?<\/h2>\n\n\n\n<p>Dans les pays anglophones comme les \u00c9tats-Unis, il est courant de r\u00e9primander les employ\u00e9s pay\u00e9s au salaire minimum qui n&#8217;ont manifestement rien \u00e0 voir avec la politique de l&#8217;entreprise. Mais n&#8217;oublie pas de les laisser un pourboire en partant.<\/p>\n\n\n\n<p><strong>Exemple :<\/strong> <em>Can I speak with your manager please? Your Wi-Fi password was hard to guess, and your bread was a bit stale.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Can I take this to go \/ have a doggy bag? Can you box this up for me?<\/h2>\n\n\n\n<p>C&#8217;est une expression cl\u00e9 que tu devrais envisager d&#8217;ajouter \u00e0 ton bagage linguistique, surtout lorsque tu voyages aux \u00c9tats-Unis. Inutile de dire que les portions en Am\u00e9rique sont d\u00e9raisonnablement grandes et que tu ne pourras jamais tout finir. Oh, comme nous savons \u00e0 quel point tout le monde aime les restes\u2026<\/p>\n\n\n\n<p><strong>Exemple : <\/strong><em>Can I have a doggy bag? I don\u2019t actually have a dog, but my roommates will love this.<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vocabulaire anglais utile au restaurant :<\/h2>\n\n\n\n<p><strong><em>A party : <\/em><\/strong>un grand groupe de personnes<\/p>\n\n\n\n<p><strong><em>Set menu :<\/em><\/strong> liste de plats que tu peux commander ensemble, \u00e0 prix fixe<\/p>\n\n\n\n<p><strong><em>A candlelit dinner :<\/em><\/strong> d\u00eener aux chandelles, un geste romantique<\/p>\n\n\n\n<p><strong><em>Early bird special :<\/em><\/strong> un repas \u00e0 prix r\u00e9duit pour une heure de repas plus t\u00f4t et moins populaire<\/p>\n\n\n\n<p><strong><em>House wine :<\/em><\/strong> vin choisi par le restaurant, g\u00e9n\u00e9ralement l&#8217;option la moins ch\u00e8re sur le menu<\/p>\n\n\n\n<p><strong><em>It\u2019s my treat :<\/em><\/strong> payer la totalit\u00e9 de l&#8217;addition<\/p>\n\n\n\n<p>\ud83c\udfa7 Fatigu\u00e9 de lire ? \u00c9coutez la version audio de l&#8217;article sur notre <a href=\"https:\/\/www.instagram.com\/reel\/Ck8YFybo5Dm\/?utm_source=ig_web_copy_link\" target=\"_blank\" rel=\"noreferrer noopener\">page Instagram<\/a> ! \ud83c\udfa7<\/p>\n\n\n\n<p><em>\u00c7a y est ! Tu es maintenant pr\u00eat \u00e0 naviguer sur la sc\u00e8ne de la restauration lors de tes voyages dans des pays anglophones. Toujours faim de plus ? Tu es insatiable ! Essaye nos <a href=\"https:\/\/www.gymglish.com\/fr\/gymglish\" target=\"_blank\" rel=\"noreferrer noopener\">le\u00e7ons d&#8217;anglais en ligne<\/a> Gymglish gratuitement pendant 7 jours.<\/em><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<div class=\"wp-block-group a9-card-cta\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"font-size:32px;font-style:normal;font-weight:300\">Apprenez l&#8217;anglais avec Gymglish \ud83c\uddec\ud83c\udde7<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-font-size is-style-fill btn-colorful btn-colorful-gg\" style=\"font-size:16px\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.gymglish.com\/fr\/gymglish\/test-anglais?rfextension=BLOG-CTA\" style=\"border-radius:50px\" target=\"_blank\" rel=\"noreferrer noopener\">TESTEZ GRATUITEMENT<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><br><\/p>\n\n\n\n<p><strong>Lire aussi sur le m\u00eame sujet :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/05\/05\/5-mots-argot-australiens\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 mots d\u2019argot australien qui vous ouvriront les portes du pays<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/11\/16\/5-mots-argot-canadien\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 mots d\u2019argot canadien \u00e0 conna\u00eetre<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2020\/07\/06\/5-insultes-pour-apprendre-anglais\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 insultes anglaises pour d\u00e9buter votre apprentissage de la langue<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/04\/13\/differences-anglais-britannique-americain\/\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019anglais britannique (GB) et l\u2019anglais am\u00e9ricain (US) : quelques diff\u00e9rences<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/05\/05\/5-mots-argot-australiens\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 mots d\u2019argot australien qui vous ouvriront les portes du pays<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2019\/04\/04\/10-faux-amis-anglais-eviter\/\" target=\"_blank\" rel=\"noreferrer noopener\">10 faux-amis en anglais \u00e0 \u00e9viter<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/08\/24\/faux-anglicismes-a-connaitre\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quelques faux anglicismes \u00e0 conna\u00eetre<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/05\/17\/mots-anglais-qui-viennent-du-francais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ces mots anglais qui viennent du fran\u00e7ais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2022\/01\/27\/5-mots-francais-viennent-langlais\" target=\"_blank\" rel=\"noreferrer noopener\">5 mots fran\u00e7ais qui viennent de l\u2019anglais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2022\/03\/24\/5-expressions-anglaises-vous-adorerez-utiliser\" target=\"_blank\" rel=\"noreferrer noopener\">5&nbsp;expressions anglaises que vous allez adorer utiliser<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2023\/03\/10\/50-facons-dutiliser-fuck-en-anglais\" target=\"_blank\" rel=\"noreferrer noopener\">50 fa\u00e7ons d\u2019utiliser&nbsp;<em>fuck&nbsp;en anglais<\/em><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2023\/03\/13\/les-origines-du-mot-fuck\" target=\"_blank\" rel=\"noreferrer noopener\">Les origines du mot&nbsp;<em>fuck<\/em><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2021\/06\/28\/4-mots-anglais-intraduisibles-francais\" target=\"_blank\" rel=\"noreferrer noopener\">4 mots anglais intraduisibles en fran\u00e7ais<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.gymglish.com\/fr\/2024\/02\/23\/guide-survie-pub-anglais\" target=\"_blank\" rel=\"noreferrer noopener\">Cheers! Le guide de survie complet pour une soir\u00e9e dans un pub anglais.<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.<\/p>\n<a href=\"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone\" class=\"more-link\">Lire la suite...<\/a>","protected":false},"author":151524248,"featured_media":31150,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[670778884,670778860],"tags":[670778952,670778951,670780276],"class_list":["post-43930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learning-things-fr","category-par-gymglish","tag-anglais","tag-apprendre-langlais","tag-restaurant","col-xs-12 col-sm-6 col-md-4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gastronomie, 5 phrases \u00e0 retenir dans un restaurant anglophone - The Gymglish blog<\/title>\n<meta name=\"description\" content=\"Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gastronomie, 5 phrases \u00e0 retenir dans un restaurant anglophone - The Gymglish blog\" \/>\n<meta property=\"og:description\" content=\"Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone\" \/>\n<meta property=\"og:site_name\" content=\"The Gymglish blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T08:33:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T09:13:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630@2x-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gymglish\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gymglish\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gastronomie, 5 phrases \u00e0 retenir dans un restaurant anglophone - The Gymglish blog","description":"Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone","og_locale":"fr_FR","og_type":"article","og_title":"Gastronomie, 5 phrases \u00e0 retenir dans un restaurant anglophone - The Gymglish blog","og_description":"Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.","og_url":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone","og_site_name":"The Gymglish blog","article_published_time":"2024-08-20T08:33:35+00:00","article_modified_time":"2025-04-03T09:13:27+00:00","og_image":[{"width":2400,"height":1260,"url":"https:\/\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630@2x-1.png","type":"image\/png"}],"author":"Gymglish","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Gymglish","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#article","isPartOf":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone"},"author":{"name":"Gymglish","@id":"https:\/\/blog.gymglish.com\/#\/schema\/person\/4c136ff52a68c7ad4668c3f89546fd61"},"headline":"Gastronomie, 5 phrases utiles \u00e0 retenir dans un restaurant anglophone","datePublished":"2024-08-20T08:33:35+00:00","dateModified":"2025-04-03T09:13:27+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone"},"wordCount":843,"commentCount":0,"image":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630%402x-1.png?fit=2400%2C1260&ssl=1","keywords":["Anglais","Apprendre l'anglais","Restaurant"],"articleSection":["Learning Things","par Gymglish"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone","url":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone","name":"Gastronomie, 5 phrases \u00e0 retenir dans un restaurant anglophone - The Gymglish blog","isPartOf":{"@id":"https:\/\/blog.gymglish.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#primaryimage"},"image":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630%402x-1.png?fit=2400%2C1260&ssl=1","datePublished":"2024-08-20T08:33:35+00:00","dateModified":"2025-04-03T09:13:27+00:00","author":{"@id":"https:\/\/blog.gymglish.com\/#\/schema\/person\/4c136ff52a68c7ad4668c3f89546fd61"},"description":"Si tu es un passionn\u00e9 de gastronomie, d\u00e9couvrir la sc\u00e8ne culinaire palpitante du pays sera la partie la plus m\u00e9morable du voyage.","breadcrumb":{"@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#primaryimage","url":"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630%402x-1.png?fit=2400%2C1260&ssl=1","contentUrl":"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630%402x-1.png?fit=2400%2C1260&ssl=1","width":2400,"height":1260},{"@type":"BreadcrumbList","@id":"https:\/\/blog.gymglish.com\/fr\/2024\/08\/20\/5-phrases-restaurant-anglophone#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.gymglish.com\/fr"},{"@type":"ListItem","position":2,"name":"par Gymglish","item":"https:\/\/blog.gymglish.com\/fr\/category\/par-gymglish\/"},{"@type":"ListItem","position":3,"name":"Gastronomie, 5 phrases utiles \u00e0 retenir dans un restaurant anglophone"}]},{"@type":"WebSite","@id":"https:\/\/blog.gymglish.com\/#website","url":"https:\/\/blog.gymglish.com\/","name":"The Gymglish blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.gymglish.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.gymglish.com\/#\/schema\/person\/4c136ff52a68c7ad4668c3f89546fd61","name":"Gymglish","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/0c11fffd2afa4dd8657d1c88cd35a1d1a98af54dfc2cf560347909a3cd2fab8f?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c11fffd2afa4dd8657d1c88cd35a1d1a98af54dfc2cf560347909a3cd2fab8f?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c11fffd2afa4dd8657d1c88cd35a1d1a98af54dfc2cf560347909a3cd2fab8f?s=96&d=identicon&r=g","caption":"Gymglish"},"description":"Laugh while you learn. Gymglish creates adaptive learning courses for languages and more. Our goal: your motivation, participation and progress.","sameAs":["http:\/\/bloggymglish.wordpress.com"],"url":"https:\/\/blog.gymglish.com\/fr\/author\/gymglishblog"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/blog.gymglish.com\/wp-content\/uploads\/2023\/02\/kitchen-1200x630%402x-1.png?fit=2400%2C1260&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/posts\/43930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/users\/151524248"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/comments?post=43930"}],"version-history":[{"count":8,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/posts\/43930\/revisions"}],"predecessor-version":[{"id":46601,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/posts\/43930\/revisions\/46601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/media\/31150"}],"wp:attachment":[{"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/media?parent=43930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/categories?post=43930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.gymglish.com\/fr\/wp-json\/wp\/v2\/tags?post=43930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}